{"id":84,"date":"2004-02-19T18:58:00","date_gmt":"2004-02-19T18:58:00","guid":{"rendered":"https:\/\/dmgmit.eu\/blog\/?p=84"},"modified":"2015-04-13T20:41:54","modified_gmt":"2015-04-13T18:41:54","slug":"la-eterna-pregunta","status":"publish","type":"post","link":"https:\/\/dmgmit.eu\/blog\/2004\/02\/19\/la-eterna-pregunta\/","title":{"rendered":"La eterna pregunta"},"content":{"rendered":"<div class=\"img-shadow\"><img decoding=\"async\" src=\"https:\/\/dmgmit.eu\/blog\/wp-content\/chriss.jpg\" alt=\"\" \/><\/div>\n<p>Dec\u00eda Chris Stevens desde la K-OSO que <em>la mayor\u00eda de nosotros hemos estado, en el lugar del accidente del amor no correspondido. Y nos hemos preguntado \u00bfC\u00f3mo he llegado yo hasta aqu\u00ed? \u00bfQu\u00e9 tiene ella de especial? \u00bfSer\u00e1 su sonrisa? \u00bfC\u00f3mo cruza las piernas? \u00bfLa forma de su tobillo? \u00bfLa conmovedora vulnerabilidad de su cintura? \u00bfCu\u00e1les son esas cosas ef\u00edmeras e ilusorias que encienden la pasi\u00f3n en el coraz\u00f3n humano? Es la eterna pregunta, el alimento perfecto para la mente en una c\u00e1lida noche de verano. El amor no mira con los ojos sino con el coraz\u00f3n. Por eso al hado Cupido siempre lo pintan ciego. S\u00ed.<\/em><br \/>\nQuiz\u00e1 por eso, en cuestiones amorosas, no queda otra que ir a tientas, vigilando de no tropezar con ning\u00fan obst\u00e1culo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dec\u00eda Chris Stevens desde la K-OSO que la mayor\u00eda de nosotros hemos estado, en el lugar del accidente del amor no correspondido. Y nos hemos preguntado \u00bfC\u00f3mo he llegado yo hasta aqu\u00ed? \u00bfQu\u00e9 tiene ella de especial? \u00bfSer\u00e1 su sonrisa? \u00bfC\u00f3mo cruza las piernas? \u00bfLa forma de su tobillo? \u00bfLa conmovedora vulnerabilidad de su cintura? \u00bfCu\u00e1les son esas cosas ef\u00edmeras e ilusorias que encienden la pasi\u00f3n en el coraz\u00f3n humano? Es la eterna pregunta, el alimento perfecto para la mente&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/dmgmit.eu\/blog\/2004\/02\/19\/la-eterna-pregunta\/\"> Leer m\u00e1s<span class=\"screen-reader-text\">  Leer m\u00e1s<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-84","post","type-post","status-publish","format-standard","hentry","category-pensamientos"],"_links":{"self":[{"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":0,"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"wp:attachment":[{"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmgmit.eu\/blog\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}